{"id":3193,"date":"2024-04-09T11:23:20","date_gmt":"2024-04-09T09:23:20","guid":{"rendered":"https:\/\/www.omop.it\/?p=3193"},"modified":"2024-10-07T16:39:56","modified_gmt":"2024-10-07T14:39:56","slug":"inserimento-master-i-e-ii-livello-linee-guida-fnomceo","status":"publish","type":"post","link":"https:\/\/www.omop.it\/index.php\/2024\/04\/09\/inserimento-master-i-e-ii-livello-linee-guida-fnomceo\/","title":{"rendered":"<strong>INSERIMENTO MASTER I\u00b0 E II\u00b0 LIVELLO &#8211; LINEE GUIDA FNOMCeO<\/strong>"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Al fine di poter inserire i corsi Master di 1\u00b0 e 2\u00b0 Livello nell&#8217;Anagrafica dell&#8217;Albo Unico Nazionale, i requisiti dei titoli di Master debbono avere i seguenti requisiti:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1)I corsi di Master pubblicizzabili sono solo quelli istituiti dalle Scuole o Dipartimenti delle Facolt\u00e0 di medicina e chirurgia e di odontoiatria e protesi dentaria di Universit\u00e0 pubbliche e private riconosciute dal MUR (ex MIUR);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2) I Master di 1\u00b0 e 2\u00b0 livello devono avere durata almeno annuale con un impegno complessivo di almeno 1500 ore corrispondenti all&#8217;acquisizione di 60 crediti formativi universitari (CFU);<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3) Rilasciano un titolo accademico di &#8220;diploma&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel caso in cui il Master non risponda ai criteri sopramenzionati, potr\u00e0 essere inserito esclusivamente all&#8217;interno del fascicolo personale del professionista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">(v. comunicazione <a href=\"https:\/\/portale.fnomceo.it\/wp-content\/uploads\/2021\/06\/COMUNICAZIONE-N-121-2021_signed.pdf\" data-type=\"link\" data-id=\"https:\/\/portale.fnomceo.it\/wp-content\/uploads\/2021\/06\/COMUNICAZIONE-N-121-2021_signed.pdf\">FNOMCeO n. 121 del 07\/06\/2021<\/a> e n. <a href=\"https:\/\/portale.fnomceo.it\/wp-content\/uploads\/2023\/12\/COM-144-2023.pdf\" data-type=\"link\" data-id=\"https:\/\/portale.fnomceo.it\/wp-content\/uploads\/2023\/12\/COM-144-2023.pdf\">144 del 14.12.2023<\/a>)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al fine di poter inserire i corsi Master di 1\u00b0 e 2\u00b0 Livello nell&#8217;Anagrafica dell&#8217;Albo Unico Nazionale, i requisiti dei titoli di Master debbono avere i seguenti requisiti: 1)I corsi di Master pubblicizzabili sono solo quelli istituiti dalle Scuole o Dipartimenti delle Facolt\u00e0 di medicina e chirurgia e di odontoiatria e protesi dentaria di Universit\u00e0 pubbliche e private riconosciute dal MUR (ex MIUR); 2) I Master di 1\u00b0 e 2\u00b0 livello devono avere durata almeno annuale con un impegno complessivo di almeno 1500 ore corrispondenti all&#8217;acquisizione di 60 crediti formativi universitari (CFU); 3) Rilasciano un titolo accademico di &#8220;diploma&#8221;.<\/p>\n","protected":false},"author":3,"featured_media":111,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"post_folder":[],"class_list":["post-3193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:12:55","action":"change-status","newStatus":"trash","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/posts\/3193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/comments?post=3193"}],"version-history":[{"count":5,"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/posts\/3193\/revisions"}],"predecessor-version":[{"id":3406,"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/posts\/3193\/revisions\/3406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/media\/111"}],"wp:attachment":[{"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/media?parent=3193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/categories?post=3193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/tags?post=3193"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.omop.it\/index.php\/wp-json\/wp\/v2\/post_folder?post=3193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}